{"id":31561,"date":"2026-01-27T13:07:04","date_gmt":"2026-01-27T12:07:04","guid":{"rendered":"https:\/\/pi3g.com\/?p=31561"},"modified":"2026-02-17T14:45:08","modified_gmt":"2026-02-17T13:45:08","slug":"trusted-platform-modules-unlocked","status":"publish","type":"post","link":"https:\/\/pi3g.com\/de\/trusted-platform-modules-unlocked\/","title":{"rendered":"Entsperrte vertrauensw\u00fcrdige Plattformmodule"},"content":{"rendered":"<p>In diesem Beitrag werden wir das Trusted Platform Module (TPM) f\u00fcr den RPi entmystifizieren, indem wir erkunden, wie dieser spezielle Hardware-Tresor Ihre digitale Identit\u00e4t sch\u00fctzt durch <em>sichere Schl\u00fcsselverwaltung,<\/em> l\u00e4sst sich nahtlos in OpenSSL und Nginx integrieren, um Webdienste zu h\u00e4rten, und bietet eine robuste Festplattenverschl\u00fcsselung, die selbst bei Diebstahl Ihrer Speichermedien gesperrt bleibt.<\/p>\n\n\n\n<p><strong>TIPP: <\/strong><a href=\"https:\/\/buyzero.de\/en\/products\/letstrust-hardware-tpm-trusted-platform-module?srsltid=AfmBOoqiZlCRjbGeZrpgrD7CkfP5Qasf-WpWlbrFIwcJusDVNM73dM-2\">Holen Sie sich noch heute ein Lets Trust TPM f\u00fcr Ihren RPi bei Buyzero!<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"478\" height=\"391\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2025\/08\/Screenshot_35.jpg\" alt=\"\" class=\"wp-image-31378\" srcset=\"https:\/\/pi3g.com\/wp-content\/uploads\/2025\/08\/Screenshot_35.jpg 478w, https:\/\/pi3g.com\/wp-content\/uploads\/2025\/08\/Screenshot_35-300x245.jpg 300w, https:\/\/pi3g.com\/wp-content\/uploads\/2025\/08\/Screenshot_35-15x12.jpg 15w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\">Passw\u00f6rter und Schl\u00fcssel<\/h1>\n\n\n\n<p>In der Kryptographie sind Passw\u00f6rter und <em>Tasten<\/em> haben unterschiedliche, aber verwandte Funktionen. Ein Passwort ist ein f\u00fcr Menschen lesbares Geheimnis (etwas, das Sie <em>kennen<\/em>), die in der Regel f\u00fcr die erste Authentifizierung verwendet werden. Da sich Menschen nur schwer zuf\u00e4llige Daten merken k\u00f6nnen, haben Passw\u00f6rter oft <em>geringe Entropie<\/em> (leicht zu knacken), was sie anf\u00e4llig f\u00fcr Erraten oder Brute-Force-Angriffe macht. Umgekehrt ist eine <em>kryptographischer Schl\u00fcssel<\/em> ist eine <em>Hochentropie<\/em> (schwer zu knacken), maschinengenerierte Zufallszeichenfolge (etwas, das Sie <em>haben<\/em>), die zum Sperren und Entsperren mathematischer Funktionen verwendet werden. In sicheren Systemen ist ein Kennwort oft nur der \u201cAusl\u00f6ser\u201d, der einen viel st\u00e4rkeren kryptografischen Schl\u00fcssel freigibt oder ableitet, so dass das System eine robuste Verschl\u00fcsselung verwenden kann, ohne dass sich der Benutzer eine 256-Bit-Kauderwelsch-Zeichenkette merken muss.<\/p>\n\n\n\n<p>Die beiden wichtigsten Methoden zur Verwendung dieser Schl\u00fcssel sind <em>symmetrisch<\/em> und <em>asymmetrisch<\/em> Verschl\u00fcsselung. Bei der symmetrischen Verschl\u00fcsselung wird ein einziger gemeinsamer geheimer Schl\u00fcssel verwendet, um Daten zu verschl\u00fcsseln und zu entschl\u00fcsseln. Sie ist au\u00dfergew\u00f6hnlich schnell und effizient und damit das \u201cArbeitspferd\u201d f\u00fcr die Verarbeitung gro\u00dfer Datenmengen. Die asymmetrische Verschl\u00fcsselung verwendet ein mathematisch verkn\u00fcpftes Paar: a <em>\u00f6ffentlicher Schl\u00fcssel<\/em> f\u00fcr die Verschl\u00fcsselung und ein <em>privater Schl\u00fcssel<\/em> f\u00fcr die Entschl\u00fcsselung. Diese Methode ist zwar viel langsamer als symmetrische Methoden, aber sie l\u00f6st das Problem der \u201cSchl\u00fcsselverteilung\u201d, da Sie Ihren \u00f6ffentlichen Schl\u00fcssel sicher mit der Welt teilen k\u00f6nnen, ohne Ihren privaten Tresor zu gef\u00e4hrden.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Wie sich symmetrische und asymmetrische Schl\u00fcssel unterscheiden<\/h1>\n\n\n\n<p>Der Grund f\u00fcr zwei separate Schl\u00fcssel ist die L\u00f6sung des \u201cSafe-in-the-Mail\u201d-Problems:&nbsp;<\/p>\n\n\n\n<p><em>Wie senden Sie jemandem ein Geheimnis, wenn Sie nicht bereits ein gemeinsames Passwort haben?<\/em><\/p>\n\n\n\n<p>Wenn Sie einen einzigen Schl\u00fcssel (symmetrisch) verwenden, m\u00fcssen Sie diesen Schl\u00fcssel zuerst an die andere Person weitergeben. Wenn ein Angreifer den Schl\u00fcssel w\u00e4hrend der \u00dcbergabe abf\u00e4ngt, ist Ihre Sicherheit gebrochen. Die asymmetrische Verschl\u00fcsselung behebt dieses Problem, indem die Funktionen \u201cSperren\u201d und \u201cEntsperren\u201d in zwei verschiedene Schl\u00fcssel aufgeteilt werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Der \u00f6ffentliche Schl\u00fcssel (Das offene Vorh\u00e4ngeschloss):<\/strong> Stellen Sie sich das wie ein offenes Vorh\u00e4ngeschloss vor, das Sie an jeden aush\u00e4ndigen, der es haben m\u00f6chte. Andere k\u00f6nnen damit ein Fach abschlie\u00dfen, aber sobald das Fach zugeklickt ist, kann die Person, die es abgeschlossen hat, es nicht mehr \u00f6ffnen.<\/li>\n\n\n\n<li><strong>Der private Schl\u00fcssel (der einzige Schl\u00fcssel):<\/strong> Dies ist der physische Schl\u00fcssel, der geheim in Ihrer Tasche bleibt. Er ist der <em>nur<\/em> das diese Vorh\u00e4ngeschl\u00f6sser \u00f6ffnen kann.<\/li>\n<\/ul>\n\n\n\n<p>Bei diesem System kann jeder auf der Welt eine Nachricht f\u00fcr Sie mit Ihrem \u201cVorh\u00e4ngeschloss\u201d verschlie\u00dfen, aber nur Sie besitzen den \u201cSchl\u00fcssel\u201d, um den Inhalt zu sehen. So k\u00f6nnen zwei Personen sicher miteinander kommunizieren, ohne das Risiko einzugehen, ein gemeinsames Passwort \u00fcber das Internet zu versenden.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Anwendungsf\u00e4lle aus der realen Welt<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Symmetrische Verschl\u00fcsselung (Das Arbeitspferd):<\/strong> Dies wird haupts\u00e4chlich verwendet f\u00fcr <em>Vollst\u00e4ndige Festplattenverschl\u00fcsselung (FDE)<\/em> auf Ihrem Computer oder Smartphone. Wenn Sie Ihr Ger\u00e4t einschalten und ein Kennwort eingeben, verwendet das System einen schnellen symmetrischen Algorithmus (wie AES-256), um die Gigabytes an Daten auf Ihrem Laufwerk sofort zu entschl\u00fcsseln, wenn Sie darauf zugreifen. So wird sichergestellt, dass bei einem Diebstahl der Hardware die Daten unlesbar bleiben.<\/li>\n\n\n\n<li><strong>Asymmetrische Verschl\u00fcsselung (The Gatekeeper):<\/strong> Dies ist die Grundlage von <em>Digitale Signaturen und sicheres Webbrowsing (HTTPS)<\/em>. Wenn Sie die Website einer Bank besuchen, verwendet Ihr Browser den \u00f6ffentlichen Schl\u00fcssel der Bank, um deren Identit\u00e4t zu verifizieren und ein tempor\u00e4res Geheimnis zu verschl\u00fcsseln. Auf diese Weise k\u00f6nnen Sie eine private Verbindung mit einem Fremden \u00fcber das Internet herstellen, ohne ihn jemals getroffen zu haben und ohne vorher ein Passwort auszutauschen.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">TPMs und Schl\u00fcsselspeicher<\/h1>\n\n\n\n<p>Im Zusammenhang mit der Verschl\u00fcsselung ist ein TPM (Trusted Platform Module) ein spezielles \u201c<em>Sicherheitsprozessor<\/em>\u201d, die l\u00e4uft <em>unabh\u00e4ngig<\/em> vom RPi und fungiert sowohl als <em>Schl\u00fcsselgenerator<\/em> und eine <em>Hardware-Tresor<\/em>. Es stellt sicher, dass sensible Schl\u00fcssel in einer isolierten Umgebung erstellt und verwendet werden, weit entfernt vom Betriebssystem, das von Malware beobachtet werden k\u00f6nnte.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Wo die Schl\u00fcssel gespeichert sind<\/h1>\n\n\n\n<p>Um zu verstehen, warum ein TPM etwas Besonderes ist, m\u00fcssen wir uns ansehen, wo die Schl\u00fcssel in einem Standardsystem (ohne TPM) im Vergleich zu einem TPM-geh\u00e4rteten System liegen:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Merkmal&nbsp;<\/strong><\/td><td><strong>Standard (Kein TPM)<\/strong><\/td><td><strong>Mit TPM 2.0<\/strong><\/td><\/tr><tr><td><strong>Generation<\/strong><\/td><td>Die Software verwendet die CPU, um Zufallszahlen auszuw\u00e4hlen.<\/td><td>Das TPM verf\u00fcgt \u00fcber einen physischen, hardwarebasierten Zufallszahlengenerator.<\/td><\/tr><tr><td><strong>Speicherort<\/strong><\/td><td>Die Schl\u00fcssel werden als Dateien auf Ihrer SD-Karte oder Festplatte gespeichert.<\/td><td>Die Schl\u00fcssel werden im TPM-Chip gespeichert oder von diesem \u201cumh\u00fcllt\u201d. **<\/td><\/tr><tr><td><strong>Exposition<\/strong><\/td><td>Um den Schl\u00fcssel zu verwenden, muss die CPU den Rohschl\u00fcssel in den System-RAM laden.<\/td><td>Der Schl\u00fcssel bleibt im TPM; die CPU sendet Daten <em>zu<\/em> das TPM zur Bearbeitung.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>** Wrapping bedeutet, dass ein Schl\u00fcssel verschl\u00fcsselt und auf Ihrer Festplatte gespeichert wird, aber in einer Form, die nur vom TPM genutzt werden kann<\/p>\n\n\n\n<p>Ihre Geheimnisse bleiben also im Wesentlichen in einem speziell entwickelten, angriffssicheren Ger\u00e4t eingeschlossen.  Sie werden niemals dem RAM ausgesetzt oder (noch schlimmer) auf Ihrer Festplatte gespeichert.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Anwendungsunterst\u00fctzung<\/h1>\n\n\n\n<p>Im Jahr 2026 hat sich die Unterst\u00fctzung von Linux-Anwendungen f\u00fcr das TPM 2.0 von experimentellen Tools zu zentralen Systemdiensten entwickelt. Im Folgenden finden Sie die wichtigsten Anwendungen und Tools, die das TPM f\u00fcr mehr Sicherheit nutzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Webserver &amp; Netzwerksicherheit<\/h2>\n\n\n\n<p>Diese Anwendungen verwenden das TPM, um sicherzustellen, dass die \u201cIdentit\u00e4t\u201d des Servers (der private Schl\u00fcssel) niemals im Klartext auf der Festplatte liegt.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nginx &amp; Apache:<\/strong> Durch die Verwendung des <strong>tpm2-openssl<\/strong> Anbieter (modern f\u00fcr OpenSSL 3.x) oder den <strong>tpm2-tss-Engine<\/strong> (Legacy) kann Nginx HTTPS-Datenverkehr mit einem privaten Schl\u00fcssel bedienen, der im TPM verbleibt.<\/li>\n\n\n\n<li><strong>OpenSSL:<\/strong> Die grundlegende Bibliothek f\u00fcr fast alle Linux-Sicherheit. Die <strong>tpm2-openssl<\/strong> Projekt erm\u00f6glicht es Standard-Befehlszeilen-Tools, Schl\u00fcssel zu erzeugen, Dokumente zu signieren und CSRs direkt auf der TPM-Hardware zu erstellen.<\/li>\n\n\n\n<li><strong>StrongSwan (VPN):<\/strong> Sch\u00fctzt die Identit\u00e4ten von VPN-Clients, indem es die privaten Authentifizierungsschl\u00fcssel im TPM speichert und so verhindert, dass sie auf einem anderen Rechner geklont werden.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Festplattenverschl\u00fcsselung &amp; Systemstart&nbsp;<\/h2>\n\n\n\n<p>Das TPM wird hier meist verwendet, um Verschl\u00fcsselungsschl\u00fcssel zu \u201cversiegeln\u201d, so dass das System nur entsperrt wird, wenn es nicht manipuliert wurde.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>systemd-cryptenroll:<\/strong> Ein modernes Tool in der systemd-Suite, mit dem Sie ein TPM 2.0-Modul in ein LUKS-verschl\u00fcsseltes Laufwerk \u201ceinschreiben\u201d k\u00f6nnen. Dies erm\u00f6glicht ein PIN-verschl\u00fcsseltes Booten.<\/li>\n\n\n\n<li><strong>systemd-creds:<\/strong> Speichert und ruft sensible Anmeldedaten (wie Datenbankpassw\u00f6rter), die von systemd-Diensten verwendet werden, sicher ab und bindet sie an das TPM.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Nachrichten\u00fcbermittlung &amp; Identit\u00e4t<\/h2>\n\n\n\n<p>Diese Tools helfen Privatpersonen, ihre digitalen Signaturen und ihre private Kommunikation zu sch\u00fctzen.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>GnuPG (GPG):<\/strong> Seit Version 2.3 unterst\u00fctzt GPG das Verschieben kompatibler Schl\u00fcssel in das TPM. Das bedeutet, dass Ihre Schl\u00fcssel zum Signieren von E-Mails oder zur Dateiverschl\u00fcsselung hardwaregesch\u00fctzt sind.<\/li>\n\n\n\n<li><strong>SSH:<\/strong> Durch die <em>tpm2-pkcs11<\/em> Schnittstelle k\u00f6nnen Benutzer ihre privaten SSH-Schl\u00fcssel im TPM speichern. Selbst wenn ein Laptop gestohlen wird, kann der Angreifer den SSH-Schl\u00fcssel nicht \u201cdumpen\u201d, um auf entfernte Server zuzugreifen.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Entwickler &amp; System Tools<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>tpm2-Tools:<\/strong> Das Standard-\u201cSchweizer Taschenmesser\u201d f\u00fcr die Interaktion mit dem TPM \u00fcber die Kommandozeile. Es enth\u00e4lt Befehle wie tpm2_getrandom zur Generierung hochwertiger Zufallszahlen f\u00fcr jede Anwendung.<\/li>\n\n\n\n<li><strong>Keylime:<\/strong> Ein Open-Source-Projekt f\u00fcr <em>Fern-Attestierung<\/em>, Damit kann ein Server seinen Zustand und seine Integrit\u00e4t mit Hilfe seines TPMs gegen\u00fcber einem entfernten Monitor nachweisen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Schutz mit Vorbehalten<\/h1>\n\n\n\n<p>In den meisten herk\u00f6mmlichen Konfigurationen h\u00e4ngt die Sicherheit Ihres Betriebssystems letztlich von folgenden Faktoren ab <em>physische Sicherheit<\/em>. Wenn ein Angreifer physisch auf den Inhalt Ihrer SD-Karte oder Festplatte zugreifen kann, kann er in der Regel Software-Passw\u00f6rter umgehen und Ihre privaten Schl\u00fcssel kopieren. Das TPM \u00e4ndert dieses Paradigma. Da das TPM manipulationssicher ist, die Schl\u00fcssel intern generiert und kryptografische Operationen innerhalb seines eigenen Siliziums durchf\u00fchrt, ist es <em>gibt niemals brauchbare Geheimnisse preis <\/em>auf den Rest des Systems. Dadurch wird die Verbindung zwischen dem Zugriff auf die Dateien und dem Zugriff auf die Verschl\u00fcsselungsschl\u00fcssel unterbrochen.<\/p>\n\n\n\n<p>Diese Sicherheit ist jedoch mit einem wichtigen Wort der Vorsicht verbunden: Wenn Sie ein TPM verwenden, wird die physische Hardware zum \u201cSingle Point of Success\u201d. Da Hochsicherheitsschl\u00fcssel \u201cnicht migrierbar\u201d sind (d.h. sie k\u00f6nnen nicht kopiert oder aus dem TPM entfernt werden), sind sie dauerhaft an diesen speziellen Chip gebunden. <em>Wenn das TPM besch\u00e4digt wird oder die Hardware verloren geht, sind Ihre Daten praktisch weg.<\/em><strong>.<\/strong> Es gibt keine Schaltfl\u00e4che \u201cPasswort vergessen\u201d f\u00fcr einen TPM-verschl\u00fcsselten Schl\u00fcssel.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Mehr dazu<\/h1>\n\n\n\n<p>Wenn Sie diesen \u00dcberblick interessant fanden, sollten Sie unseren Videokanal im Auge behalten. In den kommenden Wochen werde ich Ihnen Schritt f\u00fcr Schritt die beliebtesten Implementierungen aus der Praxis vorstellen, darunter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>H\u00e4rtung von OpenSSL:<\/strong> Generieren Sie Ihren ersten Hardware-gest\u00fctzten Schl\u00fcssel.<\/li>\n\n\n\n<li><strong>Sicheres Webhosting:<\/strong> Nginx f\u00fcr die Verwendung von TPM-residenten Zertifikaten konfigurieren.<\/li>\n\n\n\n<li><strong>Festplattenverschl\u00fcsselung:<\/strong> Einrichten<em> PIN-gesch\u00fctzte LUKS<\/em> f\u00fcr einen manipulationssicheren Stiefel.<\/li>\n<\/ul>\n\n\n\n<p>Halten Sie Ausschau nach dem ersten Video der Serie, das bald erscheint!<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Wo Sie Ihr TPM erhalten<\/h1>\n\n\n\n<p>Wenn Sie die Vorteile eines TPMs f\u00fcr den Einsatz im Jahr 2026 erkunden m\u00f6chten, stellen Sie sicher, dass Ihr TPM die TPM 2.0-Spezifikation unterst\u00fctzt, da \u00e4ltere 1.2-Module veraltet sind und keine modernen Algorithmen unterst\u00fctzen.&nbsp;<\/p>\n\n\n\n<p><strong>TIPP: <\/strong><a href=\"https:\/\/buyzero.de\/en\/products\/letstrust-hardware-tpm-trusted-platform-module?srsltid=AfmBOoqiZlCRjbGeZrpgrD7CkfP5Qasf-WpWlbrFIwcJusDVNM73dM-2\">Holen Sie sich noch heute ein Lets Trust TPM f\u00fcr Ihren RPi bei Buyzero!<\/a><\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Sichern Sie Ihre Anwendung oder Bereitstellung mit uns<\/h1>\n\n\n\n<p>Ben\u00f6tigen Sie oder Ihr Team eine Beratung zu Best Practices?  Unser Expertenteam ist bereit, Ihnen dabei zu helfen, sich in komplexen Sicherheitsarchitekturen zurechtzufinden, robuste Verschl\u00fcsselungsstandards zu implementieren und sicherzustellen, dass Ihre Implementierungen sowohl gegen digitale als auch physische Bedrohungen gewappnet sind. Kontaktieren Sie unsere Experten unter <a href=\"mailto:support@pi3g.com\">support@pi3g.com<\/a><strong> <\/strong>um noch heute mit der Sicherung Ihrer Bewerbungen zu beginnen.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Ressourcen<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/community.infineon.com\/t5\/Knowledge-Base-Articles\/Enabling-amp-testing-Infineon-OPTIGA-TPM-on-Raspberry-Pi-under-Linux\/ta-p\/623548\">https:\/\/community.infineon.com\/t5\/Knowledge-Base-Articles\/Enabling-amp-testing-Infineon-OPTIGA-TPM-on-Raspberry-Pi-under-Linux\/ta-p\/623548<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/buyzero.de\/en\/products\/letstrust-hardware-tpm-trusted-platform-module?srsltid=AfmBOoqiZlCRjbGeZrpgrD7CkfP5Qasf-WpWlbrFIwcJusDVNM73dM-2\">https:\/\/buyzero.de\/en\/products\/letstrust-hardware-tpm-trusted-platform-module?srsltid=AfmBOoqiZlCRjbGeZrpgrD7CkfP5Qasf-WpWlbrFIwcJusDVNM73dM-2<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.sstic.org\/media\/SSTIC2021\/SSTIC-actes\/protecting_ssh_authentication_with_tpm_20\/SSTIC2021-Article-protecting_ssh_authentication_with_tpm_20-iooss.pdf\">https:\/\/www.sstic.org\/media\/SSTIC2021\/SSTIC-actes\/protecting_ssh_authentication_with_tpm_20\/SSTIC2021-Article-protecting_ssh_authentication_with_tpm_20-iooss.pdf<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=jtbWnod5hoY\">https:\/\/www.youtube.com\/watch?v=jtbWnod5hoY<\/a> &nbsp; (Keylime)<\/li>\n\n\n\n<li><a href=\"https:\/\/www.infineon.com\/gated\/infineon-optiga-tpm-rpi-quickstarter-user-guide-usermanual-en_a3d6e6e3-6da2-4321-816d-8c6bcddc55ee\">https:\/\/www.infineon.com\/gated\/infineon-optiga-tpm-rpi-quickstarter-user-guide-usermanual-en_a3d6e6e3-6da2-4321-816d-8c6bcddc55ee<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/trustedcomputinggroup.org\/wp-content\/uploads\/TCG-PC-Client-Platform-Firmware-Profile-Version-1.06-Revision-52_pub-3.pdf\">https:\/\/trustedcomputinggroup.org\/wp-content\/uploads\/TCG-PC-Client-Platform-Firmware-Profile-Version-1.06-Revision-52_pub-3.pdf<\/a>&nbsp;<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>In diesem Beitrag werden wir das Trusted Platform Module (TPM) f\u00fcr den RPi entmystifizieren, indem wir untersuchen, wie dieser dedizierte Hardware-Tresor Ihre digitale Identit\u00e4t durch eine sichere Schl\u00fcsselverwaltung sch\u00fctzt, sich nahtlos in OpenSSL und Nginx integriert, um Webdienste zu h\u00e4rten, und eine robuste Festplattenverschl\u00fcsselung bietet, die selbst dann verschlossen bleibt, wenn Ihr Speichermedium physisch gestohlen wird....<\/p>","protected":false},"author":866,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-31561","post","type-post","status-publish","format-standard","hentry","category-raspberrypi-blog"],"_links":{"self":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/31561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/users\/866"}],"replies":[{"embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/comments?post=31561"}],"version-history":[{"count":2,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/31561\/revisions"}],"predecessor-version":[{"id":31597,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/31561\/revisions\/31597"}],"wp:attachment":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/media?parent=31561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/categories?post=31561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/tags?post=31561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}