{"id":27608,"date":"2020-09-01T21:06:06","date_gmt":"2020-09-01T19:06:06","guid":{"rendered":"https:\/\/pi3g.com\/?p=27608"},"modified":"2020-09-01T21:06:06","modified_gmt":"2020-09-01T19:06:06","slug":"how-to-bring-up-the-camera-and-display-on-a-compute-module-carrier-board","status":"publish","type":"post","link":"https:\/\/pi3g.com\/de\/how-to-bring-up-the-camera-and-display-on-a-compute-module-carrier-board\/","title":{"rendered":"Einschalten der Kamera und des Displays auf einer Computermodul-Tr\u00e4gerkarte"},"content":{"rendered":"<p>Wir haben unser eigenes Compute Module Carrier Board, genannt PCCB, entwickelt. Es ist kompatibel mit den Raspberry Pi Compute Modules 1 - 3 Plus und verf\u00fcgt \u00fcber eine Reihe von sehr n\u00fctzlichen Funktionen f\u00fcr den industriellen Einsatz (RS232, CAN Bus, RS485, TPM, DC\/DC Stepdown).<\/p>\n<p>Heute habe ich die Kamera und die 7-Zoll-Display-Schnittstelle \u00fcberpr\u00fcft, die wir ebenfalls auf dem Board bereitstellen.<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/Bild-1-Szene-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"519\" title=\"Bild 1 Szene 1\" style=\"display: inline; background-image: none;\" alt=\"Bild 1 Szene 1\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/Bild-1-Szene-1_thumb.jpg\" border=\"0\"><\/a><\/p>\n<p>Beachten Sie die Anschl\u00fcsse DISP1 und CAM1.<\/p>\n<h1>Hintergrundwissen \u00fcber die Kamera<\/h1>\n<p>Das Kameramodul hat zwei zus\u00e4tzliche GPIO-Pins. Diese sind bezeichnet:<\/p>\n<ul>\n<li>CAM_IO0 oder CAM_GPIO \/ CAMERA_0_SHUTDOWN<\/li>\n<li>CAM_IO1 oder LED Zeile \/ CAMERA_0_LED<\/li>\n<\/ul>\n<p>CAM_IO0 wird verwendet, um die Kamera anzusteuern und ein- und auszuschalten, wenn es erforderlich ist. Dies kann nicht manuell erfolgen, indem der Pin zur Laufzeit auf High gesetzt wird - der VideoCore Blob muss dazu in der Lage sein.<\/p>\n<p>(M\u00f6glicherweise ist es m\u00f6glich, diesen Wert immer auf \"hoch\" zu stellen, aber dann bleibt die Kamera eingeschaltet und der Stromverbrauch steigt).<\/p>\n<p>Die CAM_IO1 (LED Line) wurde fr\u00fcher bei der Kamera v1 zur Ansteuerung der LED verwendet. Laut den Raspberry Pi Ingenieuren wird sie bei der Raspberry Pi Camera v2 nicht verwendet.<\/p>\n<p>Die Pinbelegung des Kameraanschlusses (sowohl auf der Raspberry Pi Kamera als auch auf unserer Platine) ist:<\/p>\n<ul>\n<li>GND<\/li>\n<li>CAM_D0_N<\/li>\n<li>CAM_D0_P<\/li>\n<li>GND<\/li>\n<li>CAM_D1_N<\/li>\n<li>CAM_D1_P<\/li>\n<li>GND<\/li>\n<li>CAM_CK_N<\/li>\n<li>CAM_CK_P<\/li>\n<li>GND<\/li>\n<li>CAM_IO0<\/li>\n<li>CAM_IO1<\/li>\n<li>CAM_SCL<\/li>\n<li>CAM_SDA<\/li>\n<li>CAM_3V3<\/li>\n<\/ul>\n<p>Die Kamera verwendet in der Regel den internen I2C-Bus (SDA0 und SCL0 sind z. B. an GPIO0 und GPIO1 verf\u00fcgbar)<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image.png\"><img loading=\"lazy\" decoding=\"async\" width=\"437\" height=\"240\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb.png\" border=\"0\"><\/a><\/p>\n<h1>Schematische Darstellung<\/h1>\n<p>Dies sind die Schaltpl\u00e4ne unseres Hardware-Layouts:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"637\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-1.png\" border=\"0\"><\/a><\/p>\n<p>Wie Sie sehen k\u00f6nnen (und wie zuvor besprochen), verwenden wir GPIO_27 als CAM_IO0 und GPIO_26 als CAM_IO1.<\/p>\n<p>Das Display ben\u00f6tigt keine zus\u00e4tzlichen GPIO-Pins.<\/p>\n<p>Sowohl das Display als auch die Kamera verwenden den internen I2C-Bus an den Pins GPIO_1 und GPIO_0.<\/p>\n<h1>dt-blob.bin<\/h1>\n<p>Diese Datei ist ein optionaler Teil der Raspberry Pi-Bootdateien. Sie wird in \/boot abgelegt und \u00fcberschreibt die eingebaute dt-blob.bin, die in start.elf kompiliert wird.<\/p>\n<p>Er kommuniziert die GPIO-Pin-Konfiguration an die auf dem VideoCore laufende Firmware (VCOS, Video Core OS). Da Compute Module Carrier Boards, wie das unsere, h\u00e4ufig kundenspezifische Pin-Setups haben werden, <strong>diese dt-blob.bin muss bereitgestellt werden.<\/strong><\/p>\n<p>Hier finden Sie weitere Informationen zu dieser Datei, einschlie\u00dflich einer Schritt-f\u00fcr-Schritt-Anleitung zum Booten:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.raspberrypi.org\/documentation\/hardware\/computemodule\/cm-peri-sw-guide.md\">https:\/\/www.raspberrypi.org\/documentation\/hardware\/computemodule\/cm-peri-sw-guide.md<\/a><\/li>\n<li><a href=\"https:\/\/www.raspberrypi.org\/documentation\/configuration\/pin-configuration.md\">https:\/\/www.raspberrypi.org\/documentation\/configuration\/pin-configuration.md<\/a><\/li>\n<\/ul>\n<p>Raspberry Pi stellt den Quellcode f\u00fcr mehrere m\u00f6gliche Setups mit der dt-blob.bin hier zur Verf\u00fcgung:<\/p>\n<ul>\n<li><a href=\"https:\/\/github.com\/raspberrypi\/documentation\/tree\/master\/hardware\/computemodule\">https:\/\/github.com\/raspberrypi\/documentation\/tree\/master\/hardware\/computemodule<\/a><\/li>\n<\/ul>\n<p>Ich habe die Datei dt-blob-disp1-cam1.dts als Quelle ausgew\u00e4hlt und sie in dt-blob-disp1-cam1_pccb.dts umbenannt. <\/p>\n<p>Sie k\u00f6nnen die Original-Quelldatei vom Raspberry Pi hier herunterladen:<\/p>\n<ul>\n<li><a title=\"https:\/\/github.com\/raspberrypi\/documentation\/raw\/master\/hardware\/computemodule\/dt-blob-disp1-cam1.dts\" href=\"https:\/\/github.com\/raspberrypi\/documentation\/raw\/master\/hardware\/computemodule\/dt-blob-disp1-cam1.dts\">https:\/\/github.com\/raspberrypi\/documentation\/raw\/master\/hardware\/computemodule\/dt-blob-disp1-cam1.dts<\/a><\/li>\n<\/ul>\n<p>Diese Datei muss modifiziert werden, um unsere Wahl der GPIO-Pins widerzuspiegeln (was wiederum der VideoCore-Firmware erm\u00f6glicht, die Kamera einzuschalten und mit ihr zu kommunizieren).<\/p>\n<p>Diese Quelldatei enth\u00e4lt Konfigurationen f\u00fcr viele verschiedene Pi-Modelle. Wir sind nur an den Konfigurationen f\u00fcr das Rechenmodul interessiert: pins_cm3 und pins_cm<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"35\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-2.png\" border=\"0\"><\/a><\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"44\" title=\"Bild\" style=\"margin: 0px; display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-3.png\" border=\"0\"><\/a><\/p>\n<p>(Beachten Sie, dass Ihre Zeilennummern um einige Z\u00e4hler abweichen k\u00f6nnen, da ich einige zus\u00e4tzliche Dinge in die Datei aufgenommen habe, die f\u00fcr unsere Diskussion hier nicht relevant sind).<\/p>\n<p>Hier sollten Sie vier Zeilen \u00e4ndern. In unserem speziellen (!) Hardware-Setup habe ich ge\u00e4ndert:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"44\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-4.png\" border=\"0\"><\/a><\/p>\n<p>zu<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-5.png\"><img loading=\"lazy\" decoding=\"async\" width=\"746\" height=\"50\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-5.png\" border=\"0\"><\/a><\/p>\n<p>und<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-6.png\"><img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"337\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-6.png\" border=\"0\"><\/a><\/p>\n<p>zu:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-7.png\"><img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"347\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-7.png\" border=\"0\"><\/a><\/p>\n<p>Die gleichen \u00c4nderungen m\u00fcssen sowohl f\u00fcr CM3 als auch f\u00fcr CM vorgenommen werden.<\/p>\n<blockquote>\n<p>pin@p26 { function = \"output\"; termination = \"no_pulling\"; }; \/\/ CAMERA 0 LED<br \/>\npin@p27 { function = \"output\"; termination = \"no_pulling\"; }; \/\/ CAMERA 0 SHUTDOWN<\/p>\n<p>\n(...)<\/p>\n<p>pin_define@CAMERA_0_LED {<br \/>&nbsp;&nbsp;&nbsp; Typ = \"intern\";<br \/>&nbsp;&nbsp;&nbsp; Nummer = ;<br \/>\n};<br \/>\npin_define@CAMERA_0_SHUTDOWN {<br \/>&nbsp;&nbsp;&nbsp; Typ = \"intern\";<br \/>&nbsp;&nbsp;&nbsp; Nummer = ;<br \/>\n};<br \/>\npin_define@CAMERA_0_UNICAM_PORT {<br \/>&nbsp;&nbsp;&nbsp; Typ = \"intern\";<br \/>&nbsp;&nbsp;&nbsp; Zahl = ;<br \/>\n};<\/p>\n<\/blockquote>\n<p>Beachten Sie, dass Sie auch die M\u00f6glichkeit haben, einen anderen CAMERA_0_I2C_PORT und CAMERA_0_SDA_PIN \/ CAMERA_0_SCL_PIN zu verwenden, wenn Ihr Hardware-Setup dies erfordert.<\/p>\n<p>Das gleiche gilt f\u00fcr das Display, es gibt DISPLAY_SDA, DISPLAY_SCL, DISPLAY_I2C_PORT Eintr\u00e4ge, die ge\u00e4ndert werden k\u00f6nnen.<\/p>\n<p>In unserem Fall habe ich sie auf der Standardeinstellung belassen, da unser Board so konzipiert ist.<\/p>\n<h2>Kompilieren Sie diese Datei<\/h2>\n<p>F\u00fchren Sie auf dem Pi aus:<\/p>\n<blockquote>\n<p><b>sudo dtc -I dts -O dtb -o dt-blob-disp1-cam1_pccb.dtb dt-blob-disp1-cam1_pccb.dts<\/b><\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-8.png\"><img loading=\"lazy\" decoding=\"async\" width=\"916\" height=\"369\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-8.png\" border=\"0\"><\/a><\/p>\n<p>Sie erhalten dann eine Reihe von Warnungen, die Sie getrost ignorieren k\u00f6nnen.<\/p>\n<h2>dt-blob.bin installieren<\/h2>\n<blockquote>\n<p>sudo cp dt-blob-disp1-cam1_pccb.dtb \/boot\/dt-blob.bin<\/p>\n<\/blockquote>\n<p>Und Neustart. <\/p>\n<h1>Test<\/h1>\n<p>Die Stifte 26 und 27 sind nun als Ausgangsstifte eingerichtet und werden auf \"low\" gesetzt:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-9.png\"><img loading=\"lazy\" decoding=\"async\" width=\"422\" height=\"448\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-9.png\" border=\"0\"><\/a><\/p>\n<blockquote>\n<p>vcgencmd get_camera<\/p>\n<\/blockquote>\n<p>Ertr\u00e4ge:<\/p>\n<blockquote>\n<p>unterst\u00fctzt=1 erkannt=1<\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-10.png\"><img loading=\"lazy\" decoding=\"async\" width=\"427\" height=\"113\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-10.png\" border=\"0\"><\/a><\/p>\n<p>Sie k\u00f6nnen ein Standbild verwenden:<\/p>\n<blockquote>\n<p>raspistill -v -o test.jpg<\/p>\n<\/blockquote>\n<p><strong>(Vergessen Sie nicht, die Kamera auch mit raspi-config zu aktivieren!)<\/strong><\/p>\n<h2>Video-Streaming<\/h2>\n<p>Ein kleiner Bonus-Tipp. Auf Ihrem Pi k\u00f6nnen Sie einen Stream mit starten:<\/p>\n<blockquote>\n<p>raspivid -o - -t 0 -hf -w 800 -h 400 -fps 24 |cvlc -vvv -h264-fps=24 stream:\/\/\/dev\/stdin -sout '#standard{access=http,mux=ts,dst=:8160}' :demux=h264<\/p>\n<\/blockquote>\n<p>Beachte die -fps 24 und -h264-fps=24 sowohl bei raspivid als auch bei cvlc, um ihre Frameraten zu synchronisieren!<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-11.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"32\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-11.png\" border=\"0\"><\/a><\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-12.png\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"526\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-12.png\" border=\"0\"><\/a><\/p>\n<p>Verwenden Sie VLC, um den Stream anzuschauen (unter Verwendung der IP Ihres Compute Boards):<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-13.png\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"435\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-13.png\" border=\"0\"><\/a><\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-14.png\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"368\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-14.png\" border=\"0\"><\/a><\/p>\n<h1>Anzeige<\/h1>\n<p>F\u00fcr die Anzeige ist auch die Datei dt-blob.bin erforderlich.<\/p>\n<p>Ich habe eine externe Stromquelle f\u00fcr die Stromversorgung des Displays verwendet. In einer Revision der PCCB werden wir eine +5-V-Stromversorgung auf einer Stiftleiste f\u00fcr die Verwendung mit dem Display haben.<\/p>\n<p>Bitte beachten Sie, dass ich das Flexkabel der Kamera nicht verwenden konnte, um das Display zum Laufen zu bringen; es musste mit einem eigenen (kurzen) Kabel angeschlossen werden. <\/p>\n<p>Ich schalte den Strom zuerst zum Display und dann zum PCCB.<\/p>\n<p>Ber\u00fchrung funktioniert.<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/b2461dd4-c434-4882-b277-baab25b705ee.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"344\" height=\"458\" title=\"b2461dd4-c434-4882-b277-baab25b705ee\" style=\"display: inline; background-image: none;\" alt=\"b2461dd4-c434-4882-b277-baab25b705ee\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/b2461dd4-c434-4882-b277-baab25b705ee_thumb.jpg\" border=\"0\"><\/a><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/b700c161-0009-4e3f-ba0b-5759cfdbe78c.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"344\" height=\"457\" title=\"b700c161-0009-4e3f-ba0b-5759cfdbe78c\" style=\"display: inline; background-image: none;\" alt=\"b700c161-0009-4e3f-ba0b-5759cfdbe78c\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/b700c161-0009-4e3f-ba0b-5759cfdbe78c_thumb.jpg\" border=\"0\"><\/a><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/add6926c-45c2-4293-a506-3f2fdd8d752f.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"458\" title=\"add6926c-45c2-4293-a506-3f2fdd8d752f\" style=\"display: inline; background-image: none;\" alt=\"add6926c-45c2-4293-a506-3f2fdd8d752f\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/add6926c-45c2-4293-a506-3f2fdd8d752f_thumb.jpg\" border=\"0\"><\/a><\/p>\n<h2>Display und Kamera zusammen<\/h2>\n<p>Das funktioniert auch, der Kamerastream wird auch live auf dem Display angezeigt.<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-21.01.21.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"444\" title=\"WhatsApp Bild 2020-09-01 um 21.01.21\" style=\"display: inline; background-image: none;\" alt=\"WhatsApp Bild 2020-09-01 um 21.01.21\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-21.01.21_thumb.jpg\" border=\"0\"><\/a><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-21.01.20.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"444\" title=\"WhatsApp Bild 2020-09-01 um 21.01.20\" style=\"display: inline; background-image: none;\" alt=\"WhatsApp Bild 2020-09-01 um 21.01.20\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-21.01.20_thumb.jpg\" border=\"0\"><\/a><\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image-15.png\"><img loading=\"lazy\" decoding=\"async\" width=\"468\" height=\"234\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2020\/09\/image_thumb-15.png\" border=\"0\"><\/a><\/p>\n<h1>Fehler<\/h1>\n<p>beim Laufen <\/p>\n<blockquote>\n<p>raspistill -v -o test.jpg<\/p>\n<\/blockquote>\n<p>erhalten Sie:<\/p>\n<blockquote>\n<p><em>mmal_vc_component_create: Komponente 'vc.ril.camera' konnte nicht erstellt werden (1:ENOMEM)<\/em><\/p>\n<\/blockquote>\n<p>auch<\/p>\n<blockquote>\n<p>vcgencmd get_camera<\/p>\n<\/blockquote>\n<p>wird entweder angezeigt:<\/p>\n<blockquote>\n<p><em>unterst\u00fctzt=0 erkannt=0<\/em><\/p>\n<\/blockquote>\n<p>oder<\/p>\n<blockquote>\n<p><em>unterst\u00fctzt=1 erkannt=0<\/em><\/p>\n<\/blockquote>\n<p>Wenn unterst\u00fctzt=0, sollten Sie \u00fcberpr\u00fcfen, ob Ihre dt-blob.bin korrekt in \/boot installiert ist.<\/p>\n<p>Wenn detected=0, sollten Sie \u00fcberpr\u00fcfen, ob die GPIO-Pins in der Datei dt-blob.bin korrekt eingestellt sind.<\/p>\n<p>Stellen Sie au\u00dferdem sicher, dass die Kamera mit raspi-config aktiviert ist.<\/p>\n<h2>Richtige Flex-Ausrichtung<\/h2>\n<p>Die Flexkabel m\u00fcssen richtig ausgerichtet sein, um eine Verbindung herzustellen. Sie k\u00f6nnen einen Blick auf die Pinbelegung werfen und sehen, ob sich die GND- und +3V3-Pins wie erwartet verhalten, oder ob es keine Verbindung \/ keine Spannung gibt.<\/p>\n<h1>Dienstleistung von pi3g<\/h1>\n<p><font style=\"background-color: rgb(255, 255, 0);\">Wir k\u00f6nnen Ihre Hardware f\u00fcr Sie in Betrieb nehmen, Beratungsdienste anbieten oder ma\u00dfgeschneiderte Raspberry Pi-Hardware und -Software entwickeln.<strong> <\/strong><\/font><a href=\"https:\/\/pi3g.com\/de\/kontakt\/\"><font style=\"background-color: rgb(255, 255, 0);\"><strong>Kontaktieren Sie uns noch heute.<\/strong><\/font><\/a><\/p>\n<h1>Ref<\/h1>\n<ul>\n<li><a href=\"https:\/\/raspberrypi.stackexchange.com\/questions\/95420\/raspivid-es-out-set-group-pcr-is-called-too-late-stream-keeps-freezing\">https:\/\/raspberrypi.stackexchange.com\/questions\/95420\/raspivid-es-out-set-group-pcr-is-called-too-late-stream-keeps-freezing<\/a><\/li>\n<li><a href=\"https:\/\/www.raspberrypi.org\/documentation\/hardware\/display\/\">https:\/\/www.raspberrypi.org\/documentation\/hardware\/display\/<\/a><\/li>\n<li><a href=\"https:\/\/raw.githubusercontent.com\/raspberrypi\/documentation\/master\/hardware\/computemodule\/dt-blob-disp1-cam1.dts\">https:\/\/raw.githubusercontent.com\/raspberrypi\/documentation\/master\/hardware\/computemodule\/dt-blob-disp1-cam1.dts<\/a><\/li>\n<li><a href=\"https:\/\/www.raspberrypi.org\/forums\/viewtopic.php?t=164987\"><strong>https:\/\/www.raspberrypi.org\/forums\/viewtopic.php?t=164987<\/strong><\/a>&nbsp; (hier wird erkl\u00e4rt, wof\u00fcr die Leitungen CAM_IO0 und CAM_IO1 verwendet werden)<\/li>\n<li><a href=\"https:\/\/raspberrypi.stackexchange.com\/questions\/72549\/how-can-i-enable-both-the-cameras-on-the-compute-module-3\">https:\/\/raspberrypi.stackexchange.com\/questions\/72549\/how-can-i-enable-both-the-cameras-on-the-compute-module-3<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Wir haben unser eigenes Compute Module Carrier Board, genannt PCCB, entwickelt. Es ist kompatibel mit den Raspberry Pi Compute Modules 1 - 3 Plus und hat eine Reihe von sehr n\u00fctzlichen Funktionen f\u00fcr den industriellen Einsatz (RS232, CAN Bus, RS485, TPM, DC\/DC Stepdown). Heute habe ich die Kamera- und 7-Zoll-Display-Schnittstelle \u00fcberpr\u00fcft, die wir auf dem...<\/p>","protected":false},"author":830,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1,400],"tags":[878,870,873,868,874,653,879,869,872,750,877,871,422,875,876,880],"class_list":["post-27608","post","type-post","status-publish","format-standard","hentry","category-raspberrypi-blog","category-raspberry-pi-embedded-development","tag-7-display","tag-bespoke-service","tag-blob","tag-bringing-up","tag-carrier-board","tag-compute-module","tag-display","tag-hardware-software-development","tag-overlay","tag-pccb","tag-raspberry-cam-module","tag-raspberry-pi-os","tag-raspbian","tag-raspi-cam","tag-rpi-cam","tag-touchscreen"],"_links":{"self":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/27608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/users\/830"}],"replies":[{"embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/comments?post=27608"}],"version-history":[{"count":1,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/27608\/revisions"}],"predecessor-version":[{"id":27609,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/27608\/revisions\/27609"}],"wp:attachment":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/media?parent=27608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/categories?post=27608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/tags?post=27608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}