{"id":12722,"date":"2019-08-23T15:50:07","date_gmt":"2019-08-23T13:50:07","guid":{"rendered":"https:\/\/pi3g.com\/?p=12722"},"modified":"2019-08-23T15:50:07","modified_gmt":"2019-08-23T13:50:07","slug":"picockpit-v-0-11-0-picockpit-client-v0-15-6-released-live-pi-monitoring","status":"publish","type":"post","link":"https:\/\/pi3g.com\/de\/picockpit-v-0-11-0-picockpit-client-v0-15-6-released-live-pi-monitoring\/","title":{"rendered":"PiCockpit v.0.11.0 &amp; picockpit-client v0.15.6 ver\u00f6ffentlicht - Pi \u00dcberwachung live!"},"content":{"rendered":"<p>Frisch f\u00fcr Sie freigegeben - picockpit.com bietet Ihnen jetzt die M\u00f6glichkeit, bis zu 5 Pis von \u00fcberall auf der Welt (mit Internetverbindung) zu \u00fcberwachen <strong>umsonst<\/strong>!<\/p>\n<p>So sieht es aus:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-20.png\"><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"726\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-20.png\" border=\"0\"><\/a><\/p>\n<p>Die Daten (unter der Schaltfl\u00e4che \"Heartbeat\") werden live aktualisiert, derzeit jede Sekunde. <\/p>\n<h1>Wie kann ich mit der kostenlosen \u00dcberwachung meines Pis beginnen?<\/h1>\n<h2>Schritt 1: Anmeldung<\/h2>\n<p>Sie ben\u00f6tigen ein picockpit.com Konto - melden Sie sich an, indem Sie auf die Schaltfl\u00e4che \"Registrieren\" klicken:<\/p>\n<p><a href=\"https:\/\/picockpit.com\/register\"><img loading=\"lazy\" decoding=\"async\" width=\"134\" height=\"62\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-21.png\" border=\"0\"><\/a><\/p>\n<p>Anmelden. Bitte beachten Sie, dass die Passw\u00f6rter ziemlich sicher sein m\u00fcssen - in Ihrem eigenen Interesse (da weitere dynamische Kontrollfunktionen geplant sind und Sie Ihre Daten sicher haben wollen!)<\/p>\n<h2>Schritt 2: API-Schl\u00fcssel erstellen<\/h2>\n<p><strong>Hinweis: Sie m\u00fcssen dies nur einmal tun - Sie k\u00f6nnen mehrere Pis mit demselben API-Schl\u00fcssel hinzuf\u00fcgen!<\/strong><\/p>\n<p><a href=\"https:\/\/picockpit.com\/user-profile\"><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"244\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-22.png\" border=\"0\"><\/a><\/p>\n<p>Klicken Sie auf den Namen Ihres Benutzerkontos, und dann <a href=\"https:\/\/picockpit.com\/user-profile\">Profil &amp; Einstellungen<\/a><strong><\/strong>.<\/p>\n<p>Klicken Sie auf die Registerkarte API-Schl\u00fcssel:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-23.png\"><img loading=\"lazy\" decoding=\"async\" width=\"536\" height=\"177\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-21.png\" border=\"0\"><\/a><\/p>\n<p>und hier auf die Schaltfl\u00e4che API-Schl\u00fcssel hinzuf\u00fcgen.<\/p>\n<p>Geben Sie Ihr Passwort ein und klicken Sie auf API-Schl\u00fcssel erstellen:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-24.png\"><img loading=\"lazy\" decoding=\"async\" width=\"536\" height=\"290\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-22.png\" border=\"0\"><\/a><\/p>\n<p><\/p>\n<p>Wichtig: Der neue API-Schl\u00fcssel wird angezeigt <strong>f\u00fcr Sie nur dieses eine Mal <\/strong>in vollem Umfang.<\/p>\n<p>Wir <strong>sind nicht f\u00e4hig <\/strong>der Wiederherstellung des API-Schl\u00fcssels in der Datenbank - er wird gehasht (wiederum im Interesse Ihrer Sicherheit).<\/p>\n<p>Bewahren Sie es an einem sicheren Ort auf, z. B. in Ihrem Passwort-Manager.<\/p>\n<p>Sollten Sie den API-Schl\u00fcssel verlieren, machen Sie sich keine Sorgen: Derzeit k\u00f6nnen Sie eine unbegrenzte Anzahl von API-Schl\u00fcsseln erstellen. <\/p>\n<p>(Die 5-Pis-Grenze gilt allerdings f\u00fcr alle Ihre Api-Schl\u00fcssel)<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-25.png\"><img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"198\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-23.png\" border=\"0\"><\/a><\/p>\n<p>Sie haben die M\u00f6glichkeit, dem API-Schl\u00fcssel einen Namen zu geben und ihn zu l\u00f6schen, wenn Sie ihn nicht mehr ben\u00f6tigen. (Sie k\u00f6nnen ihn anhand seines Pr\u00e4fixes identifizieren - der Teil vor dem Punkt).<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-26.png\"><img loading=\"lazy\" decoding=\"async\" width=\"537\" height=\"42\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-24.png\" border=\"0\"><\/a><\/p>\n<p>Bitte beachten Sie: Die gesamte Zeichenfolge ist der API-Schl\u00fcssel. In diesem Beispiel lautet er <\/p>\n<blockquote>\n<p>mTZHcUt.T2gHh6jXZoZaaZT4YgY4JK4im8C9HTCzn<\/p>\n<\/blockquote>\n<p>Er muss genau so eingegeben werden, wie Sie ihn sehen (eventuell kopieren\/einf\u00fcgen). Gro\u00dfschreibung ist wichtig!<\/p>\n<h2>Schritt 3: Picockpit-Client auf dem Pi installieren<\/h2>\n<p>picockpit-client ist die Software, die auf Ihrem Pi l\u00e4uft, um ihn zu \u00fcberwachen und die Daten an Ihr picockpit.com Online-Konto zu senden. <\/p>\n<p>Es ist derzeit kompatibel mit Raspbian (getestet mit Buster und Jessie) - dem standardm\u00e4\u00dfigen und empfohlenen Betriebssystem f\u00fcr den Raspberry Pi <img decoding=\"async\" class=\"wlEmoticon wlEmoticon-smile\" style=\"\" alt=\"L\u00e4cheln\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/wlEmoticon-smile-2.png\"><\/p>\n<p>Ich zeige Ihnen, wie Sie es auf Ihrem Pi installieren.<\/p>\n<p>F\u00fchren Sie die folgenden Befehle aus:<\/p>\n<blockquote>\n<p>curl -L http:\/\/repository.picockpit.com\/picockpit.public.key | sudo apt-key add -<\/p>\n<p>echo \"deb http:\/\/repository.picockpit.com\/raspbian stretch main\" | sudo tee -append \/etc\/apt\/sources.list.d\/picockpit.list<\/p>\n<p>sudo apt-get update<\/p>\n<p>sudo apt-get install picockpit-client<\/p>\n<\/blockquote>\n<p>Bitte beachten Sie, dass WordPress leider Zeichen beim Posten durcheinanderbringt. Hier ist ein Screenshot dessen, was Sie eingeben m\u00fcssen:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-27.png\"><img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"205\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-25.png\" border=\"0\"><\/a><\/p>\n<p>Der zweite Befehl geht in <strong>eine <\/strong>Zeile, nicht auf zwei Zeilen aufteilen, sonst funktioniert es nicht.<\/p>\n<p>Was bewirken diese Befehle? <\/p>\n<ul>\n<li>Der Schl\u00fcssel f\u00fcr unser Repository wird hinzugef\u00fcgt.<\/li>\n<li>Das Repository wird zu Ihrem pi hinzugef\u00fcgt<\/li>\n<li>Die Paketlisten werden aktualisiert<\/li>\n<li>picockpit-client ist installiert<\/li>\n<\/ul>\n<p>Wenn in Zukunft eine neue Version des picockpit-client erscheint, k\u00f6nnen Sie einfach auf diese Version umsteigen, indem Sie <\/p>\n<ul>\n<li>sudo apt-get update &amp;&amp; sudo apt-get -only-upgrade install picockpit-client<\/li>\n<\/ul>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-28.png\"><img loading=\"lazy\" decoding=\"async\" width=\"669\" height=\"37\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-26.png\" border=\"0\"><\/a><\/p>\n<h2>Schritt 4: Picockpit-Client mit picockpit.com verbinden<\/h2>\n<p>F\u00fchren Sie diesen Befehl aus (es ist der letzte, ich verspreche es):<\/p>\n<blockquote>\n<p>sudo picockpit-client connect<\/p>\n<\/blockquote>\n<p>picockpit-client wird Sie nach Ihrem API-Schl\u00fcssel fragen. Geben Sie den API-Schl\u00fcssel ein, den Sie in Schritt 2 erhalten haben.<\/p>\n<p>Sie werden gefragt, ob Sie fortfahren m\u00f6chten - geben Sie Enter ein (oder \"y\" und dann Enter), um mit den Tests fortzufahren. <\/p>\n<p>Standardm\u00e4\u00dfig wird pidoctor (um einige grundlegende Daten \u00fcber Ihren Pi zu erhalten) im datenschutzfreundlichen Modus ausgef\u00fchrt, d.h. Ihre WiFi-Netzwerke werden nicht gescannt. <\/p>\n<p>Dann werden Sie nach einem Namen gefragt. Der Hostname des Pi wird als Standard vorgeschlagen. Sie k\u00f6nnen alles eingeben, was Sie wollen, einschlie\u00dflich UTF-8-Emojis. <\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-29.png\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"307\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-27.png\" border=\"0\"><\/a><\/p>\n<p>Wenn alles funktioniert hat, sollten Sie die folgende Meldung erhalten:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-30.png\"><img loading=\"lazy\" decoding=\"async\" width=\"649\" height=\"42\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-28.png\" border=\"0\"><\/a><\/p>\n<p>Fertig mit connect - Ihr Pi ist nun mit picockpit.com verbunden, wenn alles in Ordnung war<\/p>\n<p><strong>picockpit-client wird als Dienst installiert und startet automatisch bei jedem Start des Pi.<\/strong><\/p>\n<p>Sie m\u00fcssen diesen Schritt nur einmal f\u00fcr jeden Pi (und jede neue SD-Karte) durchf\u00fchren.<\/p>\n<p>Tipp: Sie k\u00f6nnen die SD-Karte auch auf mehrere Pis aufteilen und dann jedes einzeln einrichten - picockpit-client wei\u00df, wie das geht.<\/p>\n<p>Au\u00dferdem werden die Informationen verschl\u00fcsselt auf der SD-Karte gespeichert, um Ihre Verbindung zu picockpit.com zu sch\u00fctzen. <\/p>\n<p><\/p>\n<h2>Schritt 5: Sehen Sie sich meinen Pis auf picockpit.com an.<\/h2>\n<p>Ihr Pi ist jetzt online verf\u00fcgbar unter My Raspberry Pi's<\/p>\n<p><a href=\"https:\/\/picockpit.com\/mypis\"><img loading=\"lazy\" decoding=\"async\" width=\"303\" height=\"319\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-31.png\" border=\"0\"><\/a><\/p>\n<p><a href=\"https:\/\/picockpit.com\/mypis\">https:\/\/picockpit.com\/mypis<\/a><\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-32.png\"><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"180\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-29.png\" border=\"0\"><\/a><\/p>\n<p>Der Pi wird mit dem Modell, der Seriennummer, der \u00f6ffentlichen IP des Netzwerks, in dem er sich befindet, und den privaten IPs, die er in diesem Netzwerk hat, unter der Schaltfl\u00e4che Info angezeigt.<\/p>\n<p>Wenn Sie auf den Herzschlag klicken <a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-33.png\"><img loading=\"lazy\" decoding=\"async\" width=\"37\" height=\"33\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-30.png\" border=\"0\"><\/a>Taste:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-34.png\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"161\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-31.png\" border=\"0\"><\/a><\/p>\n<p>Sie werden die aktuellen Statistiken sehen k\u00f6nnen, die live aktualisiert werden. <\/p>\n<ul>\n<li>CPU-Auslastung<\/li>\n<li>RAM-Nutzung<\/li>\n<li>SoC Temperatur<\/li>\n<li>Festplattennutzung<\/li>\n<\/ul>\n<p>Tipp: Strg + Klick auf das Info- oder Heartbeat-Symbol schaltet alle Pis in die jeweilige Ansicht (Informationen oder Live-Statistiken).<\/p>\n<p>Sie k\u00f6nnen sich von \u00fcberall auf der Welt mit picockpit.com verbinden und Ihre Pis \u00fcberwachen, die sich ebenfalls \u00fcberall auf der Welt befinden k\u00f6nnen.<\/p>\n<p>Die Pis k\u00f6nnen sich hinter Firewalls befinden, das spielt keine Rolle. Wir verwenden MQTT (und VerneMQ als Broker), um die Magie zu erzeugen. <\/p>\n<p>Bitte beachten Sie, dass Sie JavaScript in Ihrem Browser aktivieren m\u00fcssen!<\/p>\n<h2>Bonus: noch mehr Statistiken!<\/h2>\n<p>Klicken Sie auf den einzelnen Pi (Bild oder Name), um noch mehr Statistiken zu erhalten! Wechseln Sie zur Registerkarte \"Sensor\", um Folgendes zu sehen:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-35.png\"><img loading=\"lazy\" decoding=\"async\" width=\"515\" height=\"627\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-32.png\" border=\"0\"><\/a><\/p>\n<p>Wie Sie sehen, erhalten Sie mit Picockpit derzeit folgende Leistungen - absolut kostenlos, und das f\u00fcr bis zu f\u00fcnf Pis!<\/p>\n<ul>\n<li>Wlan-Signal (Verbindungsqualit\u00e4t und Signalpegel)<\/li>\n<li>CPU-Last \u00fcber alle Kerne<\/li>\n<li>Insgesamt installierter Arbeitsspeicher (ohne Videocore-Teil)<\/li>\n<li>Verf\u00fcgbarer RAM (freier RAM)<\/li>\n<li>Netzwerk insgesamt empfangene Daten<\/li>\n<li>Netzwerk insgesamt gesendete Daten<\/li>\n<li>SoC Temperatur<\/li>\n<li>Festplatten-E\/A gesamt gelesen<\/li>\n<li>Festplatten-E\/A insgesamt geschrieben<\/li>\n<li>Root-Partition ('\/') insgesamt verf\u00fcgbar<\/li>\n<li>Root-Partition ('\/') insgesamt genutzt<\/li>\n<li>Betriebszeit des Raspberry Pi<\/li>\n<\/ul>\n<p>Die Registerkarte \"Pi-Informationen\" f\u00fcr jeden Pi gibt Ihnen zus\u00e4tzlich eine Menge Informationen - aber bitte beachten Sie, dass diese nur einmal gesammelt werden, wenn PiDoctor gestartet wird.<\/p>\n<p>(Es ist m\u00f6glich, pidoctor erneut auszuf\u00fchren, um die Informationen zu aktualisieren - dies ist ein Thema f\u00fcr einen anderen Beitrag).<\/p>\n<h1>Was k\u00f6nnen wir also damit anfangen? <\/h1>\n<h2>FLIRC-Geh\u00e4use vs. nackter Pi<\/h2>\n<p>Der FLIRC-Fall sprengt die <strong>nackt <\/strong>Pi aus dem Wasser:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-36.png\"><img loading=\"lazy\" decoding=\"async\" width=\"483\" height=\"567\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-33.png\" border=\"0\"><\/a><\/p>\n<p>Wie Sie sehen, ist die Temperatur im FLIRC-Geh\u00e4use etwa 10 \u00b0C niedriger als beim Pi 4 ohne Geh\u00e4use. <\/p>\n<p>Jetzt k\u00f6nnen Sie auch versuchen, den Pis zu laden, und die Temperaturentwicklung, die Drosselung usw. \u00fcberwachen. (und die tats\u00e4chliche Zeit, die ben\u00f6tigt wird, um die Arbeit zu beenden).<\/p>\n<p>Dazu werde ich im September ein Video drehen. <\/p>\n<h2>Online-Status von Pi<\/h2>\n<p>Wenn Ihr Pi offline geht, sehen Sie dies in Picockpit:<\/p>\n<p><a href=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image-37.png\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"127\" title=\"Bild\" style=\"display: inline; background-image: none;\" alt=\"Bild\" src=\"https:\/\/pi3g.com\/wp-content\/uploads\/2019\/08\/image_thumb-34.png\" border=\"0\"><\/a><\/p>\n<p>Und Sie werden in der Lage sein, Ma\u00dfnahmen zu ergreifen!<\/p>\n<p>Wenn gen\u00fcgend Leute danach fragen, werde ich eine <strong>Web-Push-Dienst <\/strong>damit Sie sofort benachrichtigt werden, wenn dies geschieht.<\/p>","protected":false},"excerpt":{"rendered":"<p>Frisch f\u00fcr Sie freigegeben - picockpit.com bietet Ihnen jetzt die M\u00f6glichkeit, bis zu 5 Pis von \u00fcberall auf der Welt (mit Internetanschluss) kostenlos zu \u00fcberwachen! Und so sieht es aus: Die Daten (unter dem Heartbeat Button) werden live aktualisiert, derzeit jede Sekunde. Wie kann ich meine Pis kostenlos \u00fcberwachen?...<\/p>","protected":false},"author":830,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[432,452],"tags":[702,706,700,699,705,698,696,695,694,701,703,434,697,704,707],"class_list":["post-12722","post","type-post","status-publish","format-standard","hentry","category-picockpit","category-tips-tricks","tag-api-key","tag-flirc-comparison","tag-free","tag-monitor-pi","tag-monitor-pi-temperature-online","tag-new-picockpit-release","tag-pi-connectivity","tag-pi-information","tag-pi-offline-state","tag-pi-online","tag-pi-uptime","tag-picockpit","tag-raspberry-pi-online-monitor","tag-soc-temperature","tag-temperature"],"_links":{"self":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/12722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/users\/830"}],"replies":[{"embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/comments?post=12722"}],"version-history":[{"count":1,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/12722\/revisions"}],"predecessor-version":[{"id":12723,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/posts\/12722\/revisions\/12723"}],"wp:attachment":[{"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/media?parent=12722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/categories?post=12722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pi3g.com\/de\/wp-json\/wp\/v2\/tags?post=12722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}